{"id":1238,"date":"2013-02-19T22:33:00","date_gmt":"2013-02-19T22:33:00","guid":{"rendered":"https:\/\/www.ecoterrazas.com\/blog\/?p=1238"},"modified":"2021-03-02T09:12:54","modified_gmt":"2021-03-02T09:12:54","slug":"atencion-pulgones","status":"publish","type":"post","link":"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/","title":{"rendered":"Atenci\u00f3n Pulgones\u00a1\u00a1\u00a1"},"content":{"rendered":"<p style=\"text-align: justify\">Con el despunte de la primavera, nuestras plantas, saldr\u00e1n de su letargo invernal y comenzar\u00e1n a crecer con nuevos brotes tiernos. El aumento de las horas de sol as\u00ed como unas temperaturas m\u00e1s suaves da inicio a este proceso. Estos nuevos brotes de crecimiento tiene tejidos muy blandos y son muy apetecibles para una gran variedad de insectos plaga. Uno de los m\u00e1s comunes de nuestros jardines y huertos son los pulgones, que ataca a pr\u00e1cticamente todas la plantas de jard\u00edn, huerto o interior. Es una plaga que se da preferentemente en primavera y verano, por lo que deberemos estar preparados.<\/p>\n<div style=\"text-align: center\">\n<dl id=\"\">\n<dt><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" alt=\"\" src=\"http:\/\/i.telegraph.co.uk\/multimedia\/archive\/01757\/aphid_1757448i.jpg\" width=\"421\" height=\"362\" \/><\/dt>\n<dd><em>\u00c1fido al microscopio electr\u00f3nico, con su estilete.<\/em><\/dd>\n<\/dl>\n<\/div>\n<p style=\"text-align: justify\">Los pulgones son insectos (tienen 6 patas, cabeza, t\u00f3rax y abdomen) fitopat\u00f3genos es decir causan da\u00f1os y enfermedades a la plantas de manera directa o indirecta. Se les\u00a0 denomina m\u00e1s t\u00e9cnicamente como \u00e1fidos puesto que pertenecen dentro del grupo de los Hemipteros a la familia Aphididae. Se trata de insectos que presentan una modificaci\u00f3n de sus aparato bucal, que est\u00e1 dispuesto para picar y chupar que se denomina como estilete, es por ello que los pulgones se les engloba en el grupo de las plagas de picadores-chupadores y son primos de la mosca blanca o las cochinillas, con id\u00e9ntica forma de alimentarse.<\/p>\n<figure id=\"attachment_1239\" aria-describedby=\"caption-attachment-1239\" style=\"width: 620px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/pulgon-01\/\" rel=\"attachment wp-att-1239\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-1239\" alt=\"pulgon-01\" src=\"https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/pulgon-01-1024x1024.jpg\" width=\"620\" height=\"620\" srcset=\"https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/pulgon-01-1024x1024.jpg 1024w, https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/pulgon-01-150x150.jpg 150w, https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/pulgon-01-300x300.jpg 300w, https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/pulgon-01-55x55.jpg 55w, https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/pulgon-01.jpg 1667w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><figcaption id=\"caption-attachment-1239\" class=\"wp-caption-text\">Esquema taxon\u00f3mico de un \u00e1fido \u00e1ptero<\/figcaption><\/figure>\n<p style=\"text-align: justify\">Tiene un tama\u00f1o muy peque\u00f1o de unos pocos mil\u00edmetros, y son de colores variados habitualmente verdes, negros o amarillos. Dentro de una misma especie pueden haber individuos alados y otros sin alas. Los pulgones tienen un ciclo biol\u00f3gico realmente complejo que excede lo que en este blog queremos transmitir, pero en pocas palabras pueden reproducirse sexualmente o asexualmente, es decir con y sin uni\u00f3n de sexos. Estos dos tipos de reproducci\u00f3n combinados y la capacidad de procrear varias generaciones en un a\u00f1o, a lo que sumamos su capacidad de volar los convierten en grandes colonizadores.<\/p>\n<figure style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"http:\/\/www.ent.iastate.edu\/soybeaninsects\/files\/images\/soybean%20aphid%20ant%205%20copy.jpg\" width=\"600\" height=\"400\" \/><figcaption class=\"wp-caption-text\">Colonia de pulgones y hormiga cuidadora.<\/figcaption><\/figure>\n<p style=\"text-align: justify\">De pulgones hay muchas especies, algunas son espec\u00edficas de algunos cultivos concretos y otras se alimentan de un amplio espectro de especies vegetales. Su aparato bucal consta de un afilado pico que tiene la posibilidad de atravesar los tejidos epid\u00e9rmicos de nuestras plantas, normalmente los ver\u00e1s en los brotes tiernos, capullos y env\u00e9s de las hojas, puesto que en estas ubicaciones los tejidos son mucho m\u00e1s blandos y f\u00e1ciles de atravesar. Los pulgones se alimentan de la savia vegetal que discurre por el floema y que es rica en az\u00facares que la planta produce para sus procesos vitales y crecimiento. Al alimentarse del alimento, valga la redundancia, de nuestras plantas ralentizan su crecimiento. B\u00e1sicamente extraen las proteinas de las savia, que realmente, esta muy concentrada en az\u00facares\u00a0 pero poco en proteinas, esto es el motivo por el que los pulgones excretan tal cantidad de melaza, puesto que tiene que succionar gran cantidad de savia para poder obtener los amino\u00e1cidos que permitan su r\u00e1pido crecimiento.<\/p>\n<p style=\"text-align: justify\">Ciertamente el parasitismo que ejercen sobre las plantas reduce su capacidad de crecimiento, pero resulta, que los pulgones tienen un potencial m\u00e1s nocivo la capacidad de transmitir\u00a0 a la planta otros agentes pat\u00f3genos puesto que al tener movilidad act\u00faan de vectores de enfermedades fundamentalmente virus u gracias a sus excreciones fomentan el crecimiento de hongos perjudiciales.<\/p>\n<figure id=\"attachment_1241\" aria-describedby=\"caption-attachment-1241\" style=\"width: 620px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/sam_1017\/\" rel=\"attachment wp-att-1241\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-1241\" alt=\"SAM_1017\" src=\"https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/SAM_1017.jpg\" width=\"620\" height=\"208\" srcset=\"https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/SAM_1017.jpg 1021w, https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/SAM_1017-300x101.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><figcaption id=\"caption-attachment-1241\" class=\"wp-caption-text\">Pulgones atacando una hoja de pimiento<\/figcaption><\/figure>\n<p style=\"text-align: justify\">\u00a0<b>IDENTIFICACI\u00d3N \u00a0y DA\u00d1OS CAUSADOS POR LOS PULGONES.<\/b><\/p>\n<ul style=\"text-align: justify\">\n<li>Visualmente los pulgones son muy f\u00e1cilmente apreciables, revisando el env\u00e9s de las hojas, capullos o en los brotes tiernos, los veremos normalmente apelotonados formando densas colonias.<\/li>\n<li>Veremos como las hojas del alrededor de estas colonias se vuelven como pegajosas y brillantes, esto es debido a que los pulgones excretan melaza de\u00a0 su alimentaci\u00f3n (az\u00facares que extraen de la savia). Es normal ver a hormigas orde\u00f1ando a los pulgones, estas suelen cuidar de las colonias, puesto que obtienen alimento. Esta melaza suele propiciar la aparici\u00f3n del hongo que se denomina como negrilla, tizne u holl\u00edn (<i>Cladosporium spp.,<\/i> <i>Fumaginas sp.)<\/i>, recubriendo las hojas impidiendo el normal funcionamiento de las mismas, reduciendo la capacidad de realizar la fotos\u00edntesis y propiciando la aparici\u00f3n de otros hongos pat\u00f3genos.<\/li>\n<li>Es com\u00fan ver restos de mudas de individuos, sus ciclos vitales son muy\u00a0 r\u00e1pidos, y de una manera muy acelerada es f\u00e1cil observar huevos,\u00a0 estadios juveniles (ninfas) y adultos, alados y sin alas.<\/li>\n<li>En ataques severos se produce un debilitamiento de la planta, deteni\u00e9ndose el crecimiento, las hojas se arrollan y se puede llegar a secar la planta, o producirse importantes defoliaciones.<\/li>\n<li>Los \u00e1fidos pueden transmitir m\u00e1s de un centenar de tipos de virus fitopat\u00f3genos. Los pulgones son el grupo de insectos m\u00e1s eficaz en cuanto a la transmisi\u00f3n de virosis, normalmente es realizada por las formas aladas. La identificaci\u00f3n de virus es compleja, pero normalmente ocasiona deformaciones notables en los tejidos de la planta, decoloraciones siguiendo patrones o serias podredumbres.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/pulgones1\/\" rel=\"attachment wp-att-1245\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1245\" alt=\"pulgones1\" src=\"https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/pulgones1-300x184.jpg\" width=\"300\" height=\"184\" srcset=\"https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/pulgones1-300x184.jpg 300w, https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/pulgones1.jpg 585w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify\">\u00a0Que m\u00e9todos tenemos para combatir los pulgones:<\/p>\n<p style=\"text-align: justify\"><b>TRATAMIENTOS PREVENTIVOS<\/b><\/p>\n<ol style=\"text-align: justify\">\n<li>Es mejor prevenir que curar, siempre se ha dicho, pues la observaci\u00f3n de la plantas y la detecci\u00f3n temprana facilitar\u00e1 el control de la plaga, para ello podemos de manera preventiva realizar riegos con <a href=\"https:\/\/www.ecoterrazas.com\/es\/62-huerto-urbano\" target=\"_blank\" rel=\"noopener noreferrer\">aceite de Neem<\/a>.<\/li>\n<li>Es \u00fatil el empleo de <a href=\"https:\/\/www.ecoterrazas.com\/es\/insecticidas-ecologicos\/86-trampas-adhesivas-azul.html\" target=\"_blank\" rel=\"noopener noreferrer\">tiras trampa atrapainsectos coloridas<\/a>, las amarillas y azules funcionan muy bien sobre las formas aladas, que suelen ser la primeras en llegar a las plantas.<\/li>\n<li>La escarda y limpieza de las malas hierbas es tambi\u00e9n crucial, las ortigas suelen repeler los pulgones, as\u00ed si observamos a estas tendremos un buen indicador biol\u00f3gico de la presencia de la plaga.<\/li>\n<li>Los <a href=\"https:\/\/www.ecoterrazas.com\/es\/insecticidas-ecologicos\/112-bio-extracto-de-ajo.html\" target=\"_blank\" rel=\"noopener noreferrer\">ajos <\/a>repelen a los pulgones entierra algunos en tus macetas, crecer\u00e1n y las sustancia que emiten servir\u00e1n de tratamiento preventivo.<\/li>\n<\/ol>\n<p style=\"text-align: justify\"><b>TRATAMIENTOS DE CONTROL<\/b><\/p>\n<ol style=\"text-align: justify\">\n<li>En estados iniciales se puede controlar la plaga manualmente, y mediante poda de las partes afectadas.<\/li>\n<li>Si se utilizan <a href=\"https:\/\/www.ecoterrazas.com\/es\/66-fertilizante-tillandsia\" target=\"_blank\" rel=\"noopener noreferrer\">insecticidas<\/a>, dado que los pulgones son chupadores, es interesante que estos sean de car\u00e1cter sist\u00e9mico, puesto que sus principios activos insecticidas circulan a trav\u00e9s de la savia. El Neem como hemos comentado previamente es sist\u00e9mico.<\/li>\n<li>Los tratamientos <a href=\"https:\/\/www.ecoterrazas.com\/es\/66-fertilizante-tillandsia\" target=\"_blank\" rel=\"noopener noreferrer\">insecticidas<\/a> deber\u00e1n realizarse con cierta frecuencia en los meses de primavera y verano, los tratamientos son m\u00e1s efectivos si se realizan con rapidez, a su vez aseg\u00farate si la aplicaci\u00f3n es foliar, que el env\u00e9s de las hojas se moje con el tratamiento.<\/li>\n<li>Si tu cultivo por culpa de la melaza ha sido atacado por alg\u00fan tipo de hongo, utiliza tratamientos <a href=\"https:\/\/www.ecoterrazas.com\/es\/insecticidas-ecologicos\/121-extracto-de-tomillo-rojo-fungicida.html\" target=\"_blank\" rel=\"noopener noreferrer\">fungicidas,<\/a> como pueden ser los basados en oxicloruro de cobre o caldo bordel\u00e9s. Tienes fungicidas naturales como la cola de caballo (<i>Equisetum<\/i>), Tomillo (<a href=\"https:\/\/www.ecoterrazas.com\/es\/insecticidas-ecologicos\/121-extracto-de-tomillo-rojo-fungicida.html\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Thymus<\/em><\/a>) o infusiones de ortigas (<i>Urtica) <\/i>. Una pulverizaci\u00f3n previa con <a href=\"https:\/\/www.ecoterrazas.com\/es\/insecticidas-ecologicos\/122-jabon-potasico.html\" target=\"_blank\" rel=\"noopener noreferrer\">agua ligeramente jabonosa<\/a> facilitar\u00e1 la erradicaci\u00f3n de los pulgones y el saneamiento de la planta<\/li>\n<li>Si tu cultivo es ecol\u00f3gico, el control biol\u00f3gico o la lucha integrada, es tu soluci\u00f3n, el pulg\u00f3n tiene muchos enemigos naturales que puedes adquirir. As\u00ed tienes donde elegir entre los que tienen una acci\u00f3n parasitoide de los pulgones (especies del genero <i><a href=\"https:\/\/www.ecoterrazas.com\/es\/66-fertilizante-tillandsia\" target=\"_blank\" rel=\"noopener noreferrer\">Aphidius<\/a>) y<\/i> aquellos que directamente los depredan, como pueden ser, larvas y adultos de neur\u00f3pteros (<a href=\"https:\/\/www.ecoterrazas.com\/es\/66-fertilizante-tillandsia\" target=\"_blank\" rel=\"noopener noreferrer\"><i>Chrysoperla carnae<\/i><\/a> y <i>Chrysopa formosa<\/i>), Cole\u00f3pteros coccin\u00e9lidos (<i>Coccinella septempuntata<\/i>), larvas de d\u00edpteros y varios Himen\u00f3pteros. Dentro de los entomopat\u00f3genos destaca el hongo pat\u00f3geno <i>Verticillium lecanii<\/i>.<\/li>\n<\/ol>\n<p>Todo lo que precises para la prevenci\u00f3n y erradicaci\u00f3n del pulg\u00f3n y otras plagas de manera ecol\u00f3gica lo podr\u00e1s encontrar en nuestra tienda on-line <a href=\"https:\/\/www.ecoterrazas.com\/es\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.ecoterrazas.com<\/a>.<\/p>\n<p>Un saludo y cuidado que viene el pulg\u00f3n&#8217;\u00a1\u00a1\u00a1<\/p>\n<p style=\"text-align: justify\"><b>\u00a0<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el despunte de la primavera, nuestras plantas, saldr\u00e1n de su letargo invernal y comenzar\u00e1n a crecer con nuevos brotes tiernos. El aumento de las horas de sol as\u00ed como unas temperaturas m\u00e1s suaves da inicio a este proceso. Estos nuevos brotes de crecimiento tiene tejidos muy blandos y son muy apetecibles para una gran &hellip;<\/p>\n","protected":false},"author":1,"featured_media":1240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[127,10],"tags":[130],"class_list":["post-1238","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-huerto-urbano","category-jardineria","tag-huevos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atenci\u00f3n Pulgones\u00a1\u00a1\u00a1<\/title>\n<meta name=\"description\" content=\"Con el despunte de la primavera, nuestras plantas, saldr\u00e1n de su letargo invernal y comenzar\u00e1n a crecer con nuevos brotes tiernos. El aumento de las horas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atenci\u00f3n Pulgones\u00a1\u00a1\u00a1\" \/>\n<meta property=\"og:description\" content=\"Con el despunte de la primavera, nuestras plantas, saldr\u00e1n de su letargo invernal y comenzar\u00e1n a crecer con nuevos brotes tiernos. El aumento de las horas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecoterrazas\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-19T22:33:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-02T09:12:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/SAM_1018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"817\" \/>\n\t<meta property=\"og:image:height\" content=\"469\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ecoterrazas.com\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ecoterrazas.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/atencion-pulgones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/atencion-pulgones\\\/\"},\"author\":{\"name\":\"Ecoterrazas.com\",\"@id\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/#\\\/schema\\\/person\\\/1c14febe08d983bdf01edf39f9cacb5d\"},\"headline\":\"Atenci\u00f3n Pulgones\u00a1\u00a1\u00a1\",\"datePublished\":\"2013-02-19T22:33:00+00:00\",\"dateModified\":\"2021-03-02T09:12:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/atencion-pulgones\\\/\"},\"wordCount\":1325,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/atencion-pulgones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/wp-content\\\/uploads\\\/SAM_1018.jpg\",\"keywords\":[\"huevos\"],\"articleSection\":[\"Huerto Urbano\",\"Jardiner\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/atencion-pulgones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/atencion-pulgones\\\/\",\"url\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/atencion-pulgones\\\/\",\"name\":\"Atenci\u00f3n Pulgones\u00a1\u00a1\u00a1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/atencion-pulgones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/atencion-pulgones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/wp-content\\\/uploads\\\/SAM_1018.jpg\",\"datePublished\":\"2013-02-19T22:33:00+00:00\",\"dateModified\":\"2021-03-02T09:12:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/#\\\/schema\\\/person\\\/1c14febe08d983bdf01edf39f9cacb5d\"},\"description\":\"Con el despunte de la primavera, nuestras plantas, saldr\u00e1n de su letargo invernal y comenzar\u00e1n a crecer con nuevos brotes tiernos. El aumento de las horas\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/atencion-pulgones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/atencion-pulgones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/wp-content\\\/uploads\\\/SAM_1018.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/wp-content\\\/uploads\\\/SAM_1018.jpg\",\"width\":817,\"height\":469},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/\",\"name\":\"Ecoterrazas\",\"description\":\"Plantas de aire y tendencias ecologicas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/#\\\/schema\\\/person\\\/1c14febe08d983bdf01edf39f9cacb5d\",\"name\":\"Ecoterrazas.com\",\"sameAs\":[\"https:\\\/\\\/www.ecoterrazas.com\"],\"url\":\"https:\\\/\\\/www.ecoterrazas.com\\\/blog\\\/author\\\/ecoterra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atenci\u00f3n Pulgones\u00a1\u00a1\u00a1","description":"Con el despunte de la primavera, nuestras plantas, saldr\u00e1n de su letargo invernal y comenzar\u00e1n a crecer con nuevos brotes tiernos. El aumento de las horas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/","og_locale":"es_ES","og_type":"article","og_title":"Atenci\u00f3n Pulgones\u00a1\u00a1\u00a1","og_description":"Con el despunte de la primavera, nuestras plantas, saldr\u00e1n de su letargo invernal y comenzar\u00e1n a crecer con nuevos brotes tiernos. El aumento de las horas","og_url":"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/","og_site_name":"Ecoterrazas","article_published_time":"2013-02-19T22:33:00+00:00","article_modified_time":"2021-03-02T09:12:54+00:00","og_image":[{"width":817,"height":469,"url":"https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/SAM_1018.jpg","type":"image\/jpeg"}],"author":"Ecoterrazas.com","twitter_misc":{"Escrito por":"Ecoterrazas.com","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/#article","isPartOf":{"@id":"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/"},"author":{"name":"Ecoterrazas.com","@id":"https:\/\/www.ecoterrazas.com\/blog\/#\/schema\/person\/1c14febe08d983bdf01edf39f9cacb5d"},"headline":"Atenci\u00f3n Pulgones\u00a1\u00a1\u00a1","datePublished":"2013-02-19T22:33:00+00:00","dateModified":"2021-03-02T09:12:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/"},"wordCount":1325,"commentCount":1,"image":{"@id":"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/SAM_1018.jpg","keywords":["huevos"],"articleSection":["Huerto Urbano","Jardiner\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/","url":"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/","name":"Atenci\u00f3n Pulgones\u00a1\u00a1\u00a1","isPartOf":{"@id":"https:\/\/www.ecoterrazas.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/#primaryimage"},"image":{"@id":"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/SAM_1018.jpg","datePublished":"2013-02-19T22:33:00+00:00","dateModified":"2021-03-02T09:12:54+00:00","author":{"@id":"https:\/\/www.ecoterrazas.com\/blog\/#\/schema\/person\/1c14febe08d983bdf01edf39f9cacb5d"},"description":"Con el despunte de la primavera, nuestras plantas, saldr\u00e1n de su letargo invernal y comenzar\u00e1n a crecer con nuevos brotes tiernos. El aumento de las horas","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ecoterrazas.com\/blog\/atencion-pulgones\/#primaryimage","url":"https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/SAM_1018.jpg","contentUrl":"https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/SAM_1018.jpg","width":817,"height":469},{"@type":"WebSite","@id":"https:\/\/www.ecoterrazas.com\/blog\/#website","url":"https:\/\/www.ecoterrazas.com\/blog\/","name":"Ecoterrazas","description":"Plantas de aire y tendencias ecologicas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecoterrazas.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ecoterrazas.com\/blog\/#\/schema\/person\/1c14febe08d983bdf01edf39f9cacb5d","name":"Ecoterrazas.com","sameAs":["https:\/\/www.ecoterrazas.com"],"url":"https:\/\/www.ecoterrazas.com\/blog\/author\/ecoterra\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.ecoterrazas.com\/blog\/wp-content\/uploads\/SAM_1018.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2RF8Q-jY","_links":{"self":[{"href":"https:\/\/www.ecoterrazas.com\/blog\/wp-json\/wp\/v2\/posts\/1238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecoterrazas.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecoterrazas.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecoterrazas.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecoterrazas.com\/blog\/wp-json\/wp\/v2\/comments?post=1238"}],"version-history":[{"count":4,"href":"https:\/\/www.ecoterrazas.com\/blog\/wp-json\/wp\/v2\/posts\/1238\/revisions"}],"predecessor-version":[{"id":2893,"href":"https:\/\/www.ecoterrazas.com\/blog\/wp-json\/wp\/v2\/posts\/1238\/revisions\/2893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecoterrazas.com\/blog\/wp-json\/wp\/v2\/media\/1240"}],"wp:attachment":[{"href":"https:\/\/www.ecoterrazas.com\/blog\/wp-json\/wp\/v2\/media?parent=1238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecoterrazas.com\/blog\/wp-json\/wp\/v2\/categories?post=1238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecoterrazas.com\/blog\/wp-json\/wp\/v2\/tags?post=1238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}